{"id":5889,"date":"2025-08-09T15:07:28","date_gmt":"2025-08-09T12:07:28","guid":{"rendered":"https:\/\/vendor.energy\/verification\/"},"modified":"2026-07-04T01:31:05","modified_gmt":"2026-07-03T22:31:05","slug":"verifizierungsdaten","status":"publish","type":"page","link":"https:\/\/vendor.energy\/de\/verifizierungsdaten\/","title":{"rendered":"Verifizierungsdaten"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5889\" class=\"elementor elementor-5889 elementor-5838\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fbeaad7 e-flex e-con-boxed e-con e-parent\" data-id=\"fbeaad7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c22d6c9 elementor-widget elementor-widget-html\" data-id=\"c22d6c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"vrf-section\">\n  <div class=\"tvp-container\">\n    <div class=\"vrf-panel\"\n         data-ai-page-type=\"verification-reserved-placeholder\"\n         data-ai-status=\"awaiting-independent-verification\">\n\n      <p class=\"tvp-label\">Verifizierung \u00b7 Reserviert<\/p>\n\n      <h1 class=\"tvp-h1\">Unabh&auml;ngige Verifizierung<\/h1>\n\n      <p class=\"vrf-statement\">\n        Diese Seite ist ausschlie&szlig;lich der Ver&ouml;ffentlichung von\n        Ergebnissen aus <strong>unabh&auml;ngiger Verifizierung<\/strong>\n        vorbehalten, die von unabh&auml;ngigen Laboratorien nach erfolgreicher\n        Nachbildung des Prototyps unter vereinbarten Bedingungen\n        durchgef&uuml;hrt wird. Bis zum Abschluss dieses Prozesses werden hier\n        keine Verifizierungsergebnisse ver&ouml;ffentlicht.\n      <\/p>\n\n      <hr class=\"vrf-divider\">\n\n      <span class=\"tvp-badge tvp-badge--warn\">\n        <span class=\"tvp-badge__dot\"><\/span>\n        Unabh&auml;ngige Verifizierung ausstehend\n      <\/span>\n\n    <\/div>\n  <\/div>\n<\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Verifizierung \u00b7 Reserviert Unabh&auml;ngige Verifizierung Diese Seite ist ausschlie&szlig;lich der Ver&ouml;ffentlichung von Ergebnissen aus unabh&auml;ngiger Verifizierung vorbehalten, die von unabh&auml;ngigen Laboratorien nach erfolgreicher Nachbildung des Prototyps unter vereinbarten Bedingungen durchgef&uuml;hrt wird. Bis zum Abschluss dieses Prozesses werden hier keine Verifizierungsergebnisse ver&ouml;ffentlicht. Unabh&auml;ngige Verifizierung ausstehend<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-5889","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/vendor.energy\/de\/wp-json\/wp\/v2\/pages\/5889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vendor.energy\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vendor.energy\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vendor.energy\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vendor.energy\/de\/wp-json\/wp\/v2\/comments?post=5889"}],"version-history":[{"count":16,"href":"https:\/\/vendor.energy\/de\/wp-json\/wp\/v2\/pages\/5889\/revisions"}],"predecessor-version":[{"id":26988,"href":"https:\/\/vendor.energy\/de\/wp-json\/wp\/v2\/pages\/5889\/revisions\/26988"}],"wp:attachment":[{"href":"https:\/\/vendor.energy\/de\/wp-json\/wp\/v2\/media?parent=5889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}